{"id":5058,"date":"2023-01-30T16:44:33","date_gmt":"2023-01-30T16:44:33","guid":{"rendered":"https:\/\/sdo.co.mz\/?page_id=5058"},"modified":"2025-02-03T00:03:39","modified_gmt":"2025-02-03T00:03:39","slug":"formacao-pedagogica-de-formadores","status":"publish","type":"page","link":"https:\/\/sdo.co.mz\/es\/formacion-y-desarrollo\/desarrollo-personal-profesional\/formacao-pedagogica-de-formadores\/","title":{"rendered":"Formaci\u00f3n Pedag\u00f3gica de Formadores"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"5058\" class=\"elementor elementor-5058\" data-elementor-settings=\"{&quot;ha_cmc_init_switcher&quot;:&quot;no&quot;}\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-65474a30 elementor-section-height-min-height elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"65474a30\" data-element_type=\"section\" data-e-type=\"section\" id=\"topo\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-11452ca0\" data-id=\"11452ca0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fb3f35a elementor-hidden-mobile elementor-widget elementor-widget-spacer\" data-id=\"fb3f35a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2cfc8ea1 elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"2cfc8ea1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Formaci\u00f3n y Desarrollo<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76de452 elementor-widget elementor-widget-spacer\" data-id=\"76de452\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-844e7d4 elementor-section-height-min-height elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"844e7d4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9f05a16\" data-id=\"9f05a16\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e5e8bdf elementor-widget elementor-widget-spacer\" data-id=\"e5e8bdf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1945a4c elementor-widget elementor-widget-heading\" data-id=\"1945a4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Formaci\u00f3n y Desarrollo<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a59793d elementor-widget elementor-widget-spacer\" data-id=\"a59793d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fe68b04 elementor-widget elementor-widget-heading\" data-id=\"fe68b04\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">Formaci\u00f3n Pedag\u00f3gica de Formadores\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ab868b3 elementor-widget elementor-widget-heading\" data-id=\"ab868b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-small\">Desarrollo Personal y Profesional<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0924e83 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"0924e83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-475d3bd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"475d3bd\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8afb7b5\" data-id=\"8afb7b5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2942dc2 elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"2942dc2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">Formaci\u00f3n Pedag\u00f3gica de Formadores<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-844f31b elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"844f31b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-small\">Desarrollo Personal y Profesional<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a738677 elementor-hidden-mobile elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"a738677\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ebda889 elementor-icon-list--layout-inline elementor-align-start elementor-tablet-align-start elementor-mobile-align-start elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"ebda889\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-clock\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">  Dura\u00e7\u00e3o<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">5 dias (20 horas)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"hm hm-hand-watch\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Hor\u00e1rio<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">17:00 \u00e0s 21:00<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">(P\u00f3s Laboral)<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1146b5c elementor-icon-list--layout-inline elementor-align-start elementor-tablet-align-start elementor-mobile-align-start elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"1146b5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"hm hm-location-pointer\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Local<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Hotel Afrin<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-graduation-hat\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">18.000 MT + Iva<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-51f4129 elementor-icon-list--layout-inline elementor-align-start elementor-tablet-align-start elementor-mobile-align-start elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"51f4129\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-calendar1\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">4 a 8 Mar\u00e7o 2024<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c1d2aa elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"9c1d2aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Data limite para inscri\u00e7\u00e3o - 1 Mar\u00e7o 2024<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-db727d5 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"db727d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Formadora - Tanya Americano<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b436392 elementor-widget elementor-widget-eael-adv-accordion\" data-id=\"b436392\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-adv-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"eael-adv-accordion\" id=\"eael-adv-accordion-b436392\" data-scroll-on-click=\"no\" data-scroll-speed=\"300\" data-accordion-id=\"b436392\" data-accordion-type=\"accordion\" data-toogle-speed=\"300\">\n            <div class=\"eael-accordion-list\">\n\t\t\t\t\t<div id=\"objectivos\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"0\" data-tab=\"1\" aria-controls=\"elementor-tab-content-1881\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">Objectivos<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1881\" class=\"eael-accordion-content clearfix\" data-tab=\"1\" aria-labelledby=\"objectivos\"><ul><li>Desenvolver compet\u00eancias de persuas\u00e3o de grupos e projec\u00e7\u00e3o de uma imagem de formador firme e seguro<\/li><\/ul><p><\/p><ul><li>Desenvolver compet\u00eancias de comunica\u00e7\u00e3o clara, eloquente e convicta<\/li><\/ul><p><\/p><ul><li>Treinar as habilidades de lidar com situa\u00e7\u00f5es at\u00edpicas e incomuns durante a forma\u00e7\u00e3o<\/li><\/ul><\/div>\n\t\t\t\t\t<\/div><div class=\"eael-accordion-list\">\n\t\t\t\t\t<div id=\"pblico-alvo\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"0\" data-tab=\"2\" aria-controls=\"elementor-tab-content-1882\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">P\u00fablico-Alvo<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1882\" class=\"eael-accordion-content clearfix\" data-tab=\"2\" aria-labelledby=\"pblico-alvo\"><ul><li>Docentes e Estudantes de Psicologia<\/li><\/ul><ul><li>Formadores internos<\/li><\/ul><ul><li>Estagi\u00e1rios da \u00e1rea de forma\u00e7\u00e3o<\/li><\/ul><p><\/p><ul><li>Outros Interessados<\/li><\/ul><\/div>\n\t\t\t\t\t<\/div><div class=\"eael-accordion-list\">\n\t\t\t\t\t<div id=\"metodologia\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"0\" data-tab=\"3\" aria-controls=\"elementor-tab-content-1883\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">Metodologia<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1883\" class=\"eael-accordion-content clearfix\" data-tab=\"3\" aria-labelledby=\"metodologia\"><ul><li>Metodologia activa<\/li><\/ul><ul><li>Abordagem de conceitos<\/li><\/ul><ul><li>Trabalhos individuais e em grupos (ou sub-grupos)<\/li><\/ul><p><\/p><ul><li>Estilos individuais de forma\u00e7\u00e3o<\/li><\/ul><\/div>\n\t\t\t\t\t<\/div><div class=\"eael-accordion-list\">\n\t\t\t\t\t<div id=\"contedos-programticos\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"0\" data-tab=\"4\" aria-controls=\"elementor-tab-content-1884\"><span class=\"eael-advanced-accordion-icon-closed\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-plus\"><\/i><\/span><span class=\"eael-advanced-accordion-icon-opened\"><i aria-hidden=\"true\" class=\"fa-accordion-icon fas fa-minus\"><\/i><\/span><span class=\"eael-accordion-tab-title\">Conte\u00fados Program\u00e1ticos<\/span><i aria-hidden=\"true\" class=\"fa-toggle fas fa-angle-right\"><\/i><\/div><div id=\"elementor-tab-content-1884\" class=\"eael-accordion-content clearfix\" data-tab=\"4\" aria-labelledby=\"contedos-programticos\"><ul><li><strong>1. Formador: Sistema, Contextos e Perfil<\/strong><ul><li>1.1. Formador, Contextos de Interven\u00e7\u00e3o<\/li><li>1.2. Aprendizagem, Criatividade e Empreendedorismo<\/li><\/ul><\/li><li><strong>2. Simula\u00e7\u00e3o Pedag\u00f3gica Inicial<\/strong><ul><li>2.1. Prepara\u00e7\u00e3o e Concretiza\u00e7\u00e3o das Simula\u00e7\u00f5es<\/li><li>2.2. An\u00e1lise e Projecto de Melhoria<\/li><\/ul><\/li><li><strong>3. Comunica\u00e7\u00e3o e Dinamiza\u00e7\u00e3o de Grupos em Forma\u00e7\u00e3o<\/strong><ul><li>3.1. Comunica\u00e7\u00e3o e Comportamento Relacional<\/li><li>3.2. Diversidade no Contexto de Forma\u00e7\u00e3o<\/li><\/ul><\/li><li><strong>4. Metodologias e Estrat\u00e9gias Pedag\u00f3gicas<\/strong><ul><li>4.1. M\u00e9todos e T\u00e9cnicas Pedag\u00f3gicas<\/li><li>4.2. Pedagogia e Aprendizagem inclusiva e Diferenciada<\/li><\/ul><\/li><li><strong>5. Operacionaliza\u00e7\u00e3o da Forma\u00e7\u00e3o: Do plano \u00e0 ac\u00e7\u00e3o<\/strong><ul><li>5.1. Compet\u00eancias e Objectivos Operacionais<\/li><li>5.2. Desenho do Processo de Forma\u00e7\u00e3o-Aprendizagem<\/li><\/ul><\/li><li><strong>6. Recursos Did\u00e1ticos e Multim\u00e9dia<\/strong><ul><li>6.1. Avalia\u00e7\u00e3o quantitativa e qualitativa<\/li><li>6.2. Constru\u00e7\u00e3o de Apresenta\u00e7\u00f5es Multim\u00e9dia<\/li><\/ul><\/li><li><strong>7. Avalia\u00e7\u00e3o da Forma\u00e7\u00e3o e das Aprendizagens<\/strong><ul><li>7.1. Avalia\u00e7\u00e3o Quantitativa e Qualitativa<\/li><li>7.2. Avalia\u00e7\u00e3o da Forma\u00e7\u00e3o ao Contexto de Trabalho<\/li><\/ul><\/li><li><strong>8. Simula\u00e7\u00e3o Pedag\u00f3gica final<\/strong><ul><li>8.1. Prepara\u00e7\u00e3o e Concretiza\u00e7\u00e3o das Simula\u00e7\u00f5es<\/li><li>8.2. An\u00e1lise e Prospectiva T\u00e9cnico-Pedag\u00f3gica<\/li><\/ul><\/li><\/ul><\/div>\n\t\t\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07a6d73 elementor-widget elementor-widget-spacer\" data-id=\"07a6d73\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1b19d9f elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1b19d9f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3aca87c\" data-id=\"3aca87c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ea2ed3d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ea2ed3d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f713dfb\" data-id=\"f713dfb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b489546 elementor-widget elementor-widget-eael-creative-button\" data-id=\"b489546\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-creative-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"eael-creative-button-wrapper\">\n\n            <a class=\"eael-creative-button eael-creative-button--default\" href=\"https:\/\/sdo.co.mz\/es\/formacion-y-desarrollo\/desarrollo-personal-profesional\/\" data-text=\"\">\n            \t    \n                <div class=\"creative-button-inner\">\n\n                                            <span class=\"eael-creative-button-icon-left\"><i aria-hidden=\"true\" class=\"fas fa-arrow-left\"><\/i><\/span>                    \n                    <span class=\"cretive-button-text\"><\/span>\n\n                                    <\/div>\n\t                        <\/a>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-10299d1\" data-id=\"10299d1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-00db516 elementor-widget elementor-widget-eael-creative-button\" data-id=\"00db516\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-creative-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"eael-creative-button-wrapper\">\n\n            <a class=\"eael-creative-button eael-creative-button--default\" href=\"#topo\" data-text=\"\">\n            \t    \n                <div class=\"creative-button-inner\">\n\n                                            <span class=\"eael-creative-button-icon-left\"><i aria-hidden=\"true\" class=\"fas fa-arrow-up\"><\/i><\/span>                    \n                    <span class=\"cretive-button-text\"><\/span>\n\n                                    <\/div>\n\t                        <\/a>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-94f215e elementor-widget elementor-widget-spacer\" data-id=\"94f215e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c8d2dfc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c8d2dfc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2dddf5a\" data-id=\"2dddf5a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5faa30d elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5faa30d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8e86e2d\" data-id=\"8e86e2d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56b879c elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"56b879c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon elementor-animation-grow\" href=\"https:\/\/sdo.co.mz\/es\/formacion-y-desarrollo\/desarrollo-personal-profesional\/\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-left\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7d7ca8a\" data-id=\"7d7ca8a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d763ed elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"5d763ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon elementor-animation-grow\" href=\"#topo\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-up\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-371a504f e-flex e-con-boxed e-con e-parent\" data-id=\"371a504f\" data-element_type=\"container\" data-e-type=\"container\" id=\"contacto\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b81e0a2 e-con-full e-flex e-con e-child\" data-id=\"b81e0a2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-39bf76f5 elementor-widget__width-auto elementor-widget-tablet__width-auto elementor-widget elementor-widget-heading\" data-id=\"39bf76f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Preencha o formul\u00e1rio para inscri\u00e7\u00e3o na forma\u00e7\u00e3o.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3bc552ba elementor-widget__width-auto eael-contact-form-7-button-align-left eael-contact-form-7-button-custom elementor-widget elementor-widget-eael-contact-form-7\" data-id=\"3bc552ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-contact-form-7.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"eael-contact-form-7-wrapper\">\n                <div class=\"eael-contact-form eael-contact-form-7 eael-contact-form-3bc552ba placeholder-show eael-contact-form-align-left\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f13007-o1\" lang=\"pt-PT\" dir=\"ltr\" data-wpcf7-id=\"13007\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/pages\/5058#wpcf7-f13007-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formul\u00e1rio de contacto\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/es\/wp-json\/wp\/v2\/pages\/5058#wpcf7-f13007-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"13007\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"pt_PT\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f13007-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nombre\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-telefone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Tel\u00e9fono M\u00f3vil\" value=\"\" type=\"tel\" name=\"your-telefone\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Mensaje\" name=\"your-message\"><\/textarea><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Enviar\" \/>\n<\/p><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"17\"\/><script>document.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );<\/script><\/p><input type='hidden' class='wpcf7-pum' value='{\"closepopup\":false,\"closedelay\":0,\"openpopup\":false,\"openpopup_id\":0}' \/><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"es\"\/><\/form>\n<\/div>\n<\/div>\n            <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Forma\u00e7\u00e3o e Desenvolvimento Forma\u00e7\u00e3o e Desenvolvimento Forma\u00e7\u00e3o Pedag\u00f3gica de Formadores Desenvolvimento Pessoal e Profissional Forma\u00e7\u00e3o Pedag\u00f3gica de Formadores Desenvolvimento Pessoal e Profissional Dura\u00e7\u00e3o 5 dias (20 horas) Hor\u00e1rio 17:00 \u00e0s 21:00 (P\u00f3s Laboral) Local Hotel Afrin 18.000 MT + Iva 4 a 8 Mar\u00e7o 2024 Data limite para inscri\u00e7\u00e3o &#8211; [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":5018,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-5058","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.9 (Yoast SEO v27.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Forma\u00e7\u00e3o Pedag\u00f3gica de Formadores - SDO Mo\u00e7ambique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sdo.co.mz\/es\/formacion-y-desarrollo\/desarrollo-personal-profesional\/formacao-pedagogica-de-formadores\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Forma\u00e7\u00e3o Pedag\u00f3gica de Formadores\" \/>\n<meta property=\"og:description\" content=\"Forma\u00e7\u00e3o e Desenvolvimento Forma\u00e7\u00e3o e Desenvolvimento Forma\u00e7\u00e3o Pedag\u00f3gica de Formadores Desenvolvimento Pessoal e Profissional Forma\u00e7\u00e3o Pedag\u00f3gica de Formadores Desenvolvimento Pessoal e Profissional Dura\u00e7\u00e3o 5 dias (20 horas) Hor\u00e1rio 17:00 \u00e0s 21:00 (P\u00f3s Laboral) Local Hotel Afrin 18.000 MT + Iva 4 a 8 Mar\u00e7o 2024 Data limite para inscri\u00e7\u00e3o &#8211; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sdo.co.mz\/es\/formacion-y-desarrollo\/desarrollo-personal-profesional\/formacao-pedagogica-de-formadores\/\" \/>\n<meta property=\"og:site_name\" content=\"SDO Mo\u00e7ambique\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sdo.mozambique\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-03T00:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sdo.co.mz\\\/formacao-e-desenvolvimento\\\/desenvolvimento-pessoal-profissional\\\/formacao-pedagogica-de-formadores\\\/\",\"url\":\"https:\\\/\\\/sdo.co.mz\\\/formacao-e-desenvolvimento\\\/desenvolvimento-pessoal-profissional\\\/formacao-pedagogica-de-formadores\\\/\",\"name\":\"Forma\u00e7\u00e3o Pedag\u00f3gica de Formadores - SDO Mo\u00e7ambique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sdo.co.mz\\\/#website\"},\"datePublished\":\"2023-01-30T16:44:33+00:00\",\"dateModified\":\"2025-02-03T00:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sdo.co.mz\\\/formacao-e-desenvolvimento\\\/desenvolvimento-pessoal-profissional\\\/formacao-pedagogica-de-formadores\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sdo.co.mz\\\/formacao-e-desenvolvimento\\\/desenvolvimento-pessoal-profissional\\\/formacao-pedagogica-de-formadores\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sdo.co.mz\\\/formacao-e-desenvolvimento\\\/desenvolvimento-pessoal-profissional\\\/formacao-pedagogica-de-formadores\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/sdo.co.mz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Forma\u00e7\u00e3o e Desenvolvimento\",\"item\":\"https:\\\/\\\/sdo.co.mz\\\/formacao-e-desenvolvimento\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Desenvolvimento Pessoal e Profissional\",\"item\":\"https:\\\/\\\/sdo.co.mz\\\/formacao-e-desenvolvimento\\\/desenvolvimento-pessoal-profissional\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Forma\u00e7\u00e3o Pedag\u00f3gica de Formadores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sdo.co.mz\\\/#website\",\"url\":\"https:\\\/\\\/sdo.co.mz\\\/\",\"name\":\"SDO Mo\u00e7ambique\",\"description\":\"Acreditamos no valor das PESSOAS e das ORGANIZA\u00c7\u00d5ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/sdo.co.mz\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sdo.co.mz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sdo.co.mz\\\/#organization\",\"name\":\"SDO Mo\u00e7ambique\",\"url\":\"https:\\\/\\\/sdo.co.mz\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/sdo.co.mz\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sdo.co.mz\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/sdo_logo-01-removebg-preview.png\",\"contentUrl\":\"https:\\\/\\\/sdo.co.mz\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/sdo_logo-01-removebg-preview.png\",\"width\":500,\"height\":500,\"caption\":\"SDO Mo\u00e7ambique\"},\"image\":{\"@id\":\"https:\\\/\\\/sdo.co.mz\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sdo.mozambique\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sdo.mozambique\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/sdo-moambique\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Forma\u00e7\u00e3o Pedag\u00f3gica de Formadores - SDO Mo\u00e7ambique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sdo.co.mz\/es\/formacion-y-desarrollo\/desarrollo-personal-profesional\/formacao-pedagogica-de-formadores\/","og_locale":"es_ES","og_type":"article","og_title":"Forma\u00e7\u00e3o Pedag\u00f3gica de Formadores","og_description":"Forma\u00e7\u00e3o e Desenvolvimento Forma\u00e7\u00e3o e Desenvolvimento Forma\u00e7\u00e3o Pedag\u00f3gica de Formadores Desenvolvimento Pessoal e Profissional Forma\u00e7\u00e3o Pedag\u00f3gica de Formadores Desenvolvimento Pessoal e Profissional Dura\u00e7\u00e3o 5 dias (20 horas) Hor\u00e1rio 17:00 \u00e0s 21:00 (P\u00f3s Laboral) Local Hotel Afrin 18.000 MT + Iva 4 a 8 Mar\u00e7o 2024 Data limite para inscri\u00e7\u00e3o &#8211; [&hellip;]","og_url":"https:\/\/sdo.co.mz\/es\/formacion-y-desarrollo\/desarrollo-personal-profesional\/formacao-pedagogica-de-formadores\/","og_site_name":"SDO Mo\u00e7ambique","article_publisher":"https:\/\/www.facebook.com\/sdo.mozambique\/","article_modified_time":"2025-02-03T00:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sdo.co.mz\/formacao-e-desenvolvimento\/desenvolvimento-pessoal-profissional\/formacao-pedagogica-de-formadores\/","url":"https:\/\/sdo.co.mz\/formacao-e-desenvolvimento\/desenvolvimento-pessoal-profissional\/formacao-pedagogica-de-formadores\/","name":"Forma\u00e7\u00e3o Pedag\u00f3gica de Formadores - SDO Mo\u00e7ambique","isPartOf":{"@id":"https:\/\/sdo.co.mz\/#website"},"datePublished":"2023-01-30T16:44:33+00:00","dateModified":"2025-02-03T00:03:39+00:00","breadcrumb":{"@id":"https:\/\/sdo.co.mz\/formacao-e-desenvolvimento\/desenvolvimento-pessoal-profissional\/formacao-pedagogica-de-formadores\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sdo.co.mz\/formacao-e-desenvolvimento\/desenvolvimento-pessoal-profissional\/formacao-pedagogica-de-formadores\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sdo.co.mz\/formacao-e-desenvolvimento\/desenvolvimento-pessoal-profissional\/formacao-pedagogica-de-formadores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/sdo.co.mz\/"},{"@type":"ListItem","position":2,"name":"Forma\u00e7\u00e3o e Desenvolvimento","item":"https:\/\/sdo.co.mz\/formacao-e-desenvolvimento\/"},{"@type":"ListItem","position":3,"name":"Desenvolvimento Pessoal e Profissional","item":"https:\/\/sdo.co.mz\/formacao-e-desenvolvimento\/desenvolvimento-pessoal-profissional\/"},{"@type":"ListItem","position":4,"name":"Forma\u00e7\u00e3o Pedag\u00f3gica de Formadores"}]},{"@type":"WebSite","@id":"https:\/\/sdo.co.mz\/#website","url":"https:\/\/sdo.co.mz\/","name":"Inicio - SDO Mozambique","description":"Acreditamos no valor das PESSOAS e das ORGANIZA\u00c7\u00d5ES","publisher":{"@id":"https:\/\/sdo.co.mz\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sdo.co.mz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sdo.co.mz\/#organization","name":"Inicio - SDO Mozambique","url":"https:\/\/sdo.co.mz\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sdo.co.mz\/#\/schema\/logo\/image\/","url":"https:\/\/sdo.co.mz\/wp-content\/uploads\/2022\/05\/sdo_logo-01-removebg-preview.png","contentUrl":"https:\/\/sdo.co.mz\/wp-content\/uploads\/2022\/05\/sdo_logo-01-removebg-preview.png","width":500,"height":500,"caption":"SDO Mo\u00e7ambique"},"image":{"@id":"https:\/\/sdo.co.mz\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sdo.mozambique\/","https:\/\/www.instagram.com\/sdo.mozambique\/","https:\/\/www.linkedin.com\/company\/sdo-moambique\/"]}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sdo.co.mz\/es\/wp-json\/wp\/v2\/pages\/5058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sdo.co.mz\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sdo.co.mz\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sdo.co.mz\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sdo.co.mz\/es\/wp-json\/wp\/v2\/comments?post=5058"}],"version-history":[{"count":87,"href":"https:\/\/sdo.co.mz\/es\/wp-json\/wp\/v2\/pages\/5058\/revisions"}],"predecessor-version":[{"id":18310,"href":"https:\/\/sdo.co.mz\/es\/wp-json\/wp\/v2\/pages\/5058\/revisions\/18310"}],"up":[{"embeddable":true,"href":"https:\/\/sdo.co.mz\/es\/wp-json\/wp\/v2\/pages\/5018"}],"wp:attachment":[{"href":"https:\/\/sdo.co.mz\/es\/wp-json\/wp\/v2\/media?parent=5058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}